{"id":195,"date":"2017-06-29T10:57:12","date_gmt":"2017-06-29T13:57:12","guid":{"rendered":"https:\/\/sfhera.com.br\/blog\/?p=195"},"modified":"2017-06-29T10:57:12","modified_gmt":"2017-06-29T13:57:12","slug":"gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes","status":"publish","type":"post","link":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/","title":{"rendered":"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes"},"content":{"rendered":"<p>Dentre os diversos recursos existentes em uma organiza\u00e7\u00e3o, o recurso humano tem sido trabalhado e desenvolvido dentro dos princ\u00edpios da gest\u00e3o humanizada, em que o indiv\u00edduo \u00e9 compreendido em seus aspectos biol\u00f3gicos, psicol\u00f3gicos e sociais. Ou seja, \u00e9 percebido e respeitado na sua totalidade e singularidade.<\/p>\n<p>Em um mercado cada dia mais competitivo, as organiza\u00e7\u00f5es precisam desenvolver estrat\u00e9gias que atendam \u00e0s necessidades da empresa, bem como \u00e0s necessidades e expectativas dos indiv\u00edduos que comp\u00f5em seu capital humano.<\/p>\n<p>O desafio dos gestores \u00e9 conseguir conciliar os objetivos pessoais e profissionais dos colaboradores, e manter a produtividade saud\u00e1vel da organiza\u00e7\u00e3o. As pr\u00e1ticas adotadas para se atingir esses objetivos, s\u00e3o:<\/p>\n<p>Respeitar a hist\u00f3ria e o momento de vida de cada colaborador, exercitando e estimulando a empatia na organiza\u00e7\u00e3o;<\/p>\n<p>Desenvolver rela\u00e7\u00f5es cordiais na equipe, possibilitando um ambiente agrad\u00e1vel e saud\u00e1vel, no qual todos possam se sentir pertencentes ao grupo, acarretando em maior satisfa\u00e7\u00e3o e reten\u00e7\u00e3o dos profissionais;<\/p>\n<p>Promover espa\u00e7os de escuta e de voz, em que os profissionais se sintam acolhidos e seguros para exporem suas percep\u00e7\u00f5es, sejam elas positivas ou negativas, em rela\u00e7\u00e3o aos processos, l\u00edderes, diretrizes, entre outros;<\/p>\n<p>Ajudar os colaboradores a melhorarem suas performances, por meio de feedbacks cont\u00ednuos;<\/p>\n<p>Oferecer treinamentos t\u00e9cnicos e comportamentais para uma atua\u00e7\u00e3o mais segura dos profissionais.<\/p>\n<p>Os resultados alcan\u00e7ados t\u00eam se mostrado satisfat\u00f3rios com as pr\u00e1ticas da gest\u00e3o humanizada: diminui\u00e7\u00e3o no \u00edndice de rotatividade, queda no n\u00famero de absente\u00edsmo e afastamentos, maior envolvimento e motiva\u00e7\u00e3o dos colaboradores.<\/p>\n<p>Na Top People, empresa especializada em trade marketing e recrutamento e sele\u00e7\u00e3o, em um quadro de aproximadamente 600 colaboradores, chegamos a passar dois anos sem causas trabalhistas e, por consequ\u00eancia, temos clientes cada dia mais satisfeitos com os servi\u00e7os oferecidos por nossa empresa.<\/p>\n<p>Acreditamos que o exerc\u00edcio da gest\u00e3o humanizada reflete na pr\u00e1tica do atendimento humanizado de nossos colaboradores para com nossos clientes, promovendo, assim, um c\u00edrculo virtuoso.<\/p>\n<p style=\"text-align: right;\">Fonte: Revista Melhor Gest\u00e3o de Pessoas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dentre os diversos recursos existentes em uma organiza\u00e7\u00e3o, o recurso humano tem sido trabalhado e desenvolvido dentro dos princ\u00edpios da gest\u00e3o humanizada,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":196,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[87,88,89],"class_list":["post-195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestaoenegocios","tag-gestao-humanizada","tag-gestao-de-pessoas","tag-colaboradores-e-clientes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes - Sfhera Software<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes\" \/>\n<meta property=\"og:description\" content=\"&quot;Em um mercado cada dia mais competitivo, as organiza\u00e7\u00f5es precisam desenvolver estrat\u00e9gias que atendam \u00e0s necessidades da empresa, bem como \u00e0s necessidades e expectativas dos indiv\u00edduos que comp\u00f5em seu capital humano. O desafio dos gestores \u00e9 conseguir conciliar os objetivos pessoais e profissionais dos colaboradores, e manter a produtividade saud\u00e1vel da organiza\u00e7\u00e3o.&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Sfhera Software\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sfhera\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-29T13:57:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/gest\u00e3o-pessoas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"804\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sfhera Software\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sfhera\" \/>\n<meta name=\"twitter:site\" content=\"@sfhera\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sfhera Software\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/\"},\"author\":{\"name\":\"Sfhera Software\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/0a21d0c7b6b15bda9d9c072dde915f2a\"},\"headline\":\"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes\",\"datePublished\":\"2017-06-29T13:57:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/\"},\"wordCount\":367,\"publisher\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/gest\u00e3o-pessoas.jpg\",\"keywords\":[\"gest\u00e3o humanizada\",\"gest\u00e3o de pessoas\",\"colaboradores e clientes\"],\"articleSection\":[\"Gest\u00e3o e Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/\",\"url\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/\",\"name\":\"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes - Sfhera Software\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/gest\u00e3o-pessoas.jpg\",\"datePublished\":\"2017-06-29T13:57:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/gest\u00e3o-pessoas.jpg\",\"contentUrl\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/gest\u00e3o-pessoas.jpg\",\"width\":804,\"height\":454,\"caption\":\"Gest\u00e3o de pessoas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/\",\"name\":\"Sfhera Software\",\"description\":\"Aplicativos de Gest\u00e3o para o Varejo\",\"publisher\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#organization\",\"name\":\"Sfhera Software\",\"url\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sfhera.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.sfhera.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/logo.png\",\"width\":200,\"height\":65,\"caption\":\"Sfhera Software\"},\"image\":{\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sfhera\",\"https:\\\/\\\/x.com\\\/sfhera\",\"https:\\\/\\\/br.linkedin.com\\\/company\\\/sfhera-software\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/0a21d0c7b6b15bda9d9c072dde915f2a\",\"name\":\"Sfhera Software\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1d1b13f14dd2dc5b3fb21e60579548fa4f79040171567f49ae19080fb354524?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1d1b13f14dd2dc5b3fb21e60579548fa4f79040171567f49ae19080fb354524?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1d1b13f14dd2dc5b3fb21e60579548fa4f79040171567f49ae19080fb354524?s=96&d=mm&r=g\",\"caption\":\"Sfhera Software\"},\"url\":\"https:\\\/\\\/sfhera.com.br\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes - Sfhera Software","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/","og_locale":"pt_BR","og_type":"article","og_title":"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes","og_description":"\"Em um mercado cada dia mais competitivo, as organiza\u00e7\u00f5es precisam desenvolver estrat\u00e9gias que atendam \u00e0s necessidades da empresa, bem como \u00e0s necessidades e expectativas dos indiv\u00edduos que comp\u00f5em seu capital humano. O desafio dos gestores \u00e9 conseguir conciliar os objetivos pessoais e profissionais dos colaboradores, e manter a produtividade saud\u00e1vel da organiza\u00e7\u00e3o.\"","og_url":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/","og_site_name":"Sfhera Software","article_publisher":"https:\/\/www.facebook.com\/sfhera","article_published_time":"2017-06-29T13:57:12+00:00","og_image":[{"width":804,"height":454,"url":"https:\/\/sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/gest\u00e3o-pessoas.jpg","type":"image\/jpeg"}],"author":"Sfhera Software","twitter_card":"summary_large_image","twitter_creator":"@sfhera","twitter_site":"@sfhera","twitter_misc":{"Escrito por":"Sfhera Software","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/#article","isPartOf":{"@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/"},"author":{"name":"Sfhera Software","@id":"https:\/\/sfhera.com.br\/blog\/#\/schema\/person\/0a21d0c7b6b15bda9d9c072dde915f2a"},"headline":"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes","datePublished":"2017-06-29T13:57:12+00:00","mainEntityOfPage":{"@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/"},"wordCount":367,"publisher":{"@id":"https:\/\/sfhera.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/gest\u00e3o-pessoas.jpg","keywords":["gest\u00e3o humanizada","gest\u00e3o de pessoas","colaboradores e clientes"],"articleSection":["Gest\u00e3o e Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/","url":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/","name":"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes - Sfhera Software","isPartOf":{"@id":"https:\/\/sfhera.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/#primaryimage"},"image":{"@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/gest\u00e3o-pessoas.jpg","datePublished":"2017-06-29T13:57:12+00:00","breadcrumb":{"@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/#primaryimage","url":"https:\/\/sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/gest\u00e3o-pessoas.jpg","contentUrl":"https:\/\/sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/gest\u00e3o-pessoas.jpg","width":804,"height":454,"caption":"Gest\u00e3o de pessoas"},{"@type":"BreadcrumbList","@id":"https:\/\/sfhera.com.br\/blog\/gestao-humanizada-reflete-na-relacao-entre-colaboradores-e-clientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sfhera.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gest\u00e3o humanizada reflete na rela\u00e7\u00e3o entre colaboradores e clientes"}]},{"@type":"WebSite","@id":"https:\/\/sfhera.com.br\/blog\/#website","url":"https:\/\/sfhera.com.br\/blog\/","name":"Sfhera Software","description":"Aplicativos de Gest\u00e3o para o Varejo","publisher":{"@id":"https:\/\/sfhera.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sfhera.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sfhera.com.br\/blog\/#organization","name":"Sfhera Software","url":"https:\/\/sfhera.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sfhera.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/logo.png","contentUrl":"https:\/\/www.sfhera.com.br\/blog\/wp-content\/uploads\/2017\/06\/logo.png","width":200,"height":65,"caption":"Sfhera Software"},"image":{"@id":"https:\/\/sfhera.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sfhera","https:\/\/x.com\/sfhera","https:\/\/br.linkedin.com\/company\/sfhera-software"]},{"@type":"Person","@id":"https:\/\/sfhera.com.br\/blog\/#\/schema\/person\/0a21d0c7b6b15bda9d9c072dde915f2a","name":"Sfhera Software","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/b1d1b13f14dd2dc5b3fb21e60579548fa4f79040171567f49ae19080fb354524?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1d1b13f14dd2dc5b3fb21e60579548fa4f79040171567f49ae19080fb354524?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1d1b13f14dd2dc5b3fb21e60579548fa4f79040171567f49ae19080fb354524?s=96&d=mm&r=g","caption":"Sfhera Software"},"url":"https:\/\/sfhera.com.br\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/posts\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":1,"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/posts\/195\/revisions"}],"predecessor-version":[{"id":197,"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/posts\/195\/revisions\/197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/media\/196"}],"wp:attachment":[{"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/media?parent=195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/categories?post=195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sfhera.com.br\/blog\/wp-json\/wp\/v2\/tags?post=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}